{"id":3060,"date":"2018-11-23T09:08:50","date_gmt":"2018-11-23T09:08:50","guid":{"rendered":"https:\/\/www.wasteyourtime.co\/?page_id=3060"},"modified":"2021-02-25T09:24:06","modified_gmt":"2021-02-25T09:24:06","slug":"z","status":"publish","type":"page","link":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/","title":{"rendered":"Z"},"content":{"rendered":"<figure id=\"attachment_3726\" aria-describedby=\"caption-attachment-3726\" style=\"width: 398px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3726 size-full\" title=\"All financial terms in the letter &quot;Z&quot;. Everything a trader or investor must know.\" src=\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg\" alt=\"Z\" width=\"398\" height=\"688\" srcset=\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg 398w, https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24-174x300.jpg 174w, https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24-370x640.jpg 370w\" sizes=\"auto, (max-width: 398px) 100vw, 398px\" \/><figcaption id=\"caption-attachment-3726\" class=\"wp-caption-text\">All financial terms in the letter &#8220;Z&#8221;. Everything a trader or investor must know.<\/figcaption><\/figure>\n<p>[wpb_childpages]<\/p>\n<div class=\"clr\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[wpb_childpages]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":2931,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-3060","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Z - Traders-Paradise<\/title>\n<meta name=\"description\" content=\"All financial terms in the letter &quot;Z&quot;. Everything a trader or investor must know.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Z - Traders-Paradise\" \/>\n<meta property=\"og:description\" content=\"All financial terms in the letter &quot;Z&quot;. Everything a trader or investor must know.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/\" \/>\n<meta property=\"og:site_name\" content=\"Traders-Paradise\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TradersParadisecom\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-25T09:24:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Traders_Paradis\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/\",\"url\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/\",\"name\":\"Z - Traders-Paradise\",\"isPartOf\":{\"@id\":\"https:\/\/traders-paradise.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg\",\"datePublished\":\"2018-11-23T09:08:50+00:00\",\"dateModified\":\"2021-02-25T09:24:06+00:00\",\"description\":\"All financial terms in the letter \\\"Z\\\". Everything a trader or investor must know.\",\"breadcrumb\":{\"@id\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#primaryimage\",\"url\":\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg\",\"contentUrl\":\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg\",\"width\":398,\"height\":688,\"caption\":\"Z\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/traders-paradise.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trading Dictionary\",\"item\":\"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Z\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/traders-paradise.com\/magazine\/#website\",\"url\":\"https:\/\/traders-paradise.com\/magazine\/\",\"name\":\"Traders-Paradise\",\"description\":\"Talking Algo Trader\",\"publisher\":{\"@id\":\"https:\/\/traders-paradise.com\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/traders-paradise.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/traders-paradise.com\/magazine\/#organization\",\"name\":\"Traders-Paradise\",\"url\":\"https:\/\/traders-paradise.com\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/traders-paradise.com\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2019\/07\/cropped-TP-Full-Landscape-transparent.png\",\"contentUrl\":\"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2019\/07\/cropped-TP-Full-Landscape-transparent.png\",\"width\":3816,\"height\":1402,\"caption\":\"Traders-Paradise\"},\"image\":{\"@id\":\"https:\/\/traders-paradise.com\/magazine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TradersParadisecom\",\"https:\/\/x.com\/Traders_Paradis\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Z - Traders-Paradise","description":"All financial terms in the letter \"Z\". Everything a trader or investor must know.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/","og_locale":"en_GB","og_type":"article","og_title":"Z - Traders-Paradise","og_description":"All financial terms in the letter \"Z\". Everything a trader or investor must know.","og_url":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/","og_site_name":"Traders-Paradise","article_publisher":"https:\/\/www.facebook.com\/TradersParadisecom","article_modified_time":"2021-02-25T09:24:06+00:00","og_image":[{"url":"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Traders_Paradis","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/","url":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/","name":"Z - Traders-Paradise","isPartOf":{"@id":"https:\/\/traders-paradise.com\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#primaryimage"},"image":{"@id":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#primaryimage"},"thumbnailUrl":"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg","datePublished":"2018-11-23T09:08:50+00:00","dateModified":"2021-02-25T09:24:06+00:00","description":"All financial terms in the letter \"Z\". Everything a trader or investor must know.","breadcrumb":{"@id":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#primaryimage","url":"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg","contentUrl":"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2018\/11\/a-24.jpg","width":398,"height":688,"caption":"Z"},{"@type":"BreadcrumbList","@id":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/z\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/traders-paradise.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Trading Dictionary","item":"https:\/\/traders-paradise.com\/magazine\/trading-dictionary\/"},{"@type":"ListItem","position":3,"name":"Z"}]},{"@type":"WebSite","@id":"https:\/\/traders-paradise.com\/magazine\/#website","url":"https:\/\/traders-paradise.com\/magazine\/","name":"Traders-Paradise","description":"Talking Algo Trader","publisher":{"@id":"https:\/\/traders-paradise.com\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/traders-paradise.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/traders-paradise.com\/magazine\/#organization","name":"Traders-Paradise","url":"https:\/\/traders-paradise.com\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/traders-paradise.com\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2019\/07\/cropped-TP-Full-Landscape-transparent.png","contentUrl":"https:\/\/traders-paradise.com\/magazine\/wp-content\/uploads\/2019\/07\/cropped-TP-Full-Landscape-transparent.png","width":3816,"height":1402,"caption":"Traders-Paradise"},"image":{"@id":"https:\/\/traders-paradise.com\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TradersParadisecom","https:\/\/x.com\/Traders_Paradis"]}]}},"_links":{"self":[{"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/pages\/3060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/comments?post=3060"}],"version-history":[{"count":1,"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/pages\/3060\/revisions"}],"predecessor-version":[{"id":25988,"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/pages\/3060\/revisions\/25988"}],"up":[{"embeddable":true,"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/pages\/2931"}],"wp:attachment":[{"href":"https:\/\/traders-paradise.com\/magazine\/wp-json\/wp\/v2\/media?parent=3060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}